{"id":2818,"date":"2025-09-30T14:20:39","date_gmt":"2025-09-30T12:20:39","guid":{"rendered":"https:\/\/www.kirchleitn.com\/location-per-eventi-in-montagna-in-carinzia\/"},"modified":"2025-11-06T10:54:23","modified_gmt":"2025-11-06T09:54:23","slug":"location-per-eventi-in-montagna-in-carinzia","status":"publish","type":"page","link":"https:\/\/www.kirchleitn.com\/it\/location-per-eventi-in-montagna-in-carinzia\/","title":{"rendered":"Location per eventi in montagna in Carinzia"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:10em;--awb-padding-right:8em;--awb-padding-bottom:2em;--awb-padding-left:8em;--awb-min-height:700px;--awb-background-color:rgba(79,74,74,0.56);--awb-background-image:linear-gradient(180deg, rgba(79,74,74,0.38) 0%,rgba(79,74,74,0.22) 100%);--awb-flex-wrap:wrap;--awb-filter:brightness(99%) contrast(111%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:brightness(100%) contrast(118%);\" ><div class=\"awb-background-slider\" data-type=\"container\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5900\" data-animation-speed=\"800\" data-direction=\"down\" style=\"--awb-image-position:50% 57%;mix-blend-mode:overlay;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal.webp\" class=\"awb-background-slider__image\" alt=\"Mit Blumen geschm\u00fcckte St\u00fchle und festliche Dekoration f\u00fcr eine Hochzeit im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1536x1024.webp 1536w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal.webp 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg\" class=\"awb-background-slider__image\" alt=\"Romantisch dekorierte Location f\u00fcr Hochzeiten und besondere Anl\u00e4sse im Slow Travel Resort Kirchleitn in K\u00e4rnten.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-300x200.jpg 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-768x512.jpg 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-1024x683.jpg 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events.webp\" class=\"awb-background-slider__image\" alt=\"Brautpaar l\u00e4uft \u00fcber die Bad Kleinkirchheimer Alm \u2013 unvergessliche Hochzeitsmomente inmitten der K\u00e4rntner Berglandschaft.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-1536x1024.webp 1536w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events.webp 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp\" class=\"awb-background-slider__image\" alt=\"Eventlocation am Berg in K\u00e4rnten, G\u00e4ste am Feiern ausgelassen im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-800x534.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp\" class=\"awb-background-slider__image\" alt=\"Seminarraum im Slow Travel Resort Kirchleitn \u2013 ideale Location f\u00fcr Tagungen, Workshops und Firmenveranstaltungen in K\u00e4rnten.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1536x1024.webp 1536w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-color:var(--awb-color1);--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p style=\"text-align: center;\">Le feste vanno celebrate quando capitano!<\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-highlight fusion-animate-once fusion-highlight-underline fusion-title-size-one\" style=\"--awb-text-color:var(--awb-color2);--awb-highlight-color:var(--awb-color5);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:60px;\" data-highlight=\"underline\"><h1 class=\"fusion-title-heading title-heading-center\" style=\"font-family:&quot;HarlowSerifplane&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;text-shadow:4px 4px 5px var(--awb-color8);\"><span class=\"fusion-highlighted-text-prefix\"><\/span> <span class=\"fusion-highlighted-text-wrapper\"><span class=\"fusion-highlighted-text\">Location per eventi in montagna <\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d=\"M8.1,146.2c0,0,240.6-55.6,479-13.8\"><\/path><\/svg><\/span> <span class=\"fusion-highlighted-text-postfix\">in Carinzia | Bad Kleinkirchheim<\/span><\/h1><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-medium-visibility fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:10em;--awb-padding-right:8em;--awb-padding-bottom:2em;--awb-padding-left:8em;--awb-padding-top-small:2em;--awb-padding-right-small:2em;--awb-padding-bottom-small:2em;--awb-padding-left-small:2em;--awb-min-height:700px;--awb-min-height-small:400px;--awb-background-color:rgba(79,74,74,0.66);--awb-background-image:linear-gradient(180deg, rgba(79,74,74,0.47) 0%,rgba(79,74,74,0.42) 100%);--awb-flex-wrap:wrap;--awb-filter:brightness(99%) contrast(111%);--awb-filter-transition:filter 0.3s ease;--awb-filter-hover:brightness(100%) contrast(118%);\" ><div class=\"awb-background-slider\" data-type=\"container\" data-loop=\"yes\" data-animation=\"fade\" data-slideshow-speed=\"5900\" data-animation-speed=\"800\" data-direction=\"down\" style=\"--awb-image-position:50% 57%;mix-blend-mode:overlay;\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal.webp\" class=\"awb-background-slider__image\" alt=\"Mit Blumen geschm\u00fcckte St\u00fchle und festliche Dekoration f\u00fcr eine Hochzeit im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal-1536x1024.webp 1536w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal.webp 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg\" class=\"awb-background-slider__image\" alt=\"Romantisch dekorierte Location f\u00fcr Hochzeiten und besondere Anl\u00e4sse im Slow Travel Resort Kirchleitn in K\u00e4rnten.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-300x200.jpg 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-768x512.jpg 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-1024x683.jpg 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp\" class=\"awb-background-slider__image\" alt=\"Eventlocation am Berg in K\u00e4rnten, G\u00e4ste am Feiern ausgelassen im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-800x534.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6.webp\" class=\"awb-background-slider__image\" alt=\"Berghochzeit in den Nockbergen. Detailaufnahme eines Brautstrau\u00dfes in festlicher Umgebung \u2013 Hochzeitsfeier in der Eventlocation Tenne im Slow Travel Resort Kirchleitn in K\u00e4rnten.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_6.webp 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2.jpg\" class=\"awb-background-slider__image\" alt=\"Sektgl\u00e4ser und Blumenarrangement auf Stehtischen im Freien \u2013 Feier im Au\u00dfenbereich des Slow Travel Resorts Kirchleitn in Bad Kleinkirchheim.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-300x200.jpg 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-768x512.jpg 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-1024x683.jpg 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><div class=\"swiper-slide\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp\" class=\"awb-background-slider__image\" alt=\"Seminarraum im Slow Travel Resort Kirchleitn \u2013 ideale Location f\u00fcr Tagungen, Workshops und Firmenveranstaltungen in K\u00e4rnten.\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1024x683.webp 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung-1536x1024.webp 1536w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp 1920w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-center fusion-title-highlight fusion-animate-once fusion-highlight-underline fusion-title-size-paragraph\" style=\"--awb-text-color:var(--awb-color2);--awb-highlight-color:var(--awb-color5);--awb-margin-top-small:2em;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\" data-highlight=\"underline\"><p class=\"fusion-title-heading title-heading-center title-heading-tag\" style=\"font-family:&quot;HarlowSerifplane&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;text-shadow:4px 4px 5px var(--awb-color8);\"><span class=\"fusion-highlighted-text-prefix\"><\/span> <span class=\"fusion-highlighted-text-wrapper\"><span class=\"fusion-highlighted-text\">Location per eventi<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d=\"M8.1,146.2c0,0,240.6-55.6,479-13.8\"><\/path><\/svg><\/span> <span class=\"fusion-highlighted-text-postfix\"> in montagna in Carinzia | Bad Kleinkirchheim<\/span><\/p><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Location unica per eventi in montagna in Carinzia \u2013 festeggia nel cuore dei monti Nockberge<\/h2><\/div><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;\"><span style=\"font-size: 1em; letter-spacing: 0px;\">Immersi nel parco della biosfera UNESCO Nockberge, vi offriamo lo spazio perfetto per il vostro evento o festa.<\/span><\/h3><\/div><div class=\"fusion-text fusion-text-2\"><p><span style=\"letter-spacing: 0.3px;\"><b>Pianificazione professionale e assistenza personalizzata, combinate con l&#8217;ospitalit\u00e0 austriaca, garantiscono momenti indimenticabili nella nostra location per eventi in montagna.<\/b><\/span><\/p>\n<p>Che si tratti di matrimoni da favola con momenti da brivido, compleanni importanti con un massimo di 500 persone, anniversari, un battesimo in famiglia o un evento di team building\u2026<\/p>\n<p><i>Nel Slow Travel Resort Kirchleitn nascono momenti da ricordare con piacere, onesti, cordiali e autentici.<\/i><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:4em;--awb-padding-right:6em;--awb-padding-bottom:4em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-min-height:600px;--awb-background-image:linear-gradient(180deg, rgba(79,74,74,0.65) 0%,rgba(111,149,113,0.76) 100%),url(https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hochzeitssaal.webp);;--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-align-content-space-evenly fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-start\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Le nostre affascinanti location per eventi per matrimoni, feste di famiglia ed eventi aziendali in Carinzia:<\/h2><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"--awb-popover-heading-background-color:var(--awb-color2);--awb-popover-content-background-color:rgba(111,149,113,0.3);--awb-popover-text-color:var(--awb-color7);--awb-popover-border-color:var(--awb-color1);\" class=\"awb-image-hotspots awb-image-hotspots-1\"><div class=\"awb-image-hotspots-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg\" alt=\"Location decorata in modo romantico per matrimoni e occasioni speciali nello Slow Travel Resort Kirchleitn in Carinzia.\" width=\"1200\" height=\"800\" title=\"Festeggiare il matrimonio nella location per eventi Kirchleitn\" class=\"awb-image-hotspots-image wp-image-2821\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-300x200.jpg 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-768x512.jpg 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-1024x683.jpg 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"\/><a style=\"--awb-hotspot-text-color:var(--awb-color2);--awb-hotspot-background-color:var(--awb-color6);--awb-pos-x:25.0%;--awb-pos-y:0.0%;\" class=\"awb-image-hotspots-hotspot awb-image-hotspots-hotspot-1\" role=\"button\" tabindex=\"0\" data-awb-toggle-image-hotspot-popover=\"true\" data-title=\"Tenne\" data-content=\"Mit 288 m\u00b2 Fl\u00e4che und Platz f\u00fcr bis zu 500 Personen stehend oder 250 Personen sitzend ist die Tenne die ideale Location f\u00fcr gr\u00f6\u00dfere Events wie Hochzeiten, Weihnachtsfeiern oder Seminare.\" data-trigger=\"hover focus\" data-placement=\"auto bottom\"><i class=\"fa-glass-cheers fas\"><\/i> 150-500 persone<\/a><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:1em;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"--awb-popover-heading-background-color:var(--awb-color2);--awb-popover-content-background-color:rgba(111,149,113,0.3);--awb-popover-text-color:var(--awb-color7);--awb-popover-border-color:var(--awb-color1);\" class=\"awb-image-hotspots awb-image-hotspots-2\"><div class=\"awb-image-hotspots-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt.jpg\" alt=\"Skisportwoche in K\u00e4rnten, t\u00e4glich frische Verpflegung im Restaurant Bauernwirt\" width=\"1200\" height=\"800\" title=\"Restaurant Bauernwirt\" class=\"awb-image-hotspots-image wp-image-1425\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-300x200.jpg 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-768x512.jpg 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt-1024x683.jpg 1024w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Gastraum-Bauernwirt.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"\/><a style=\"--awb-hotspot-text-color:var(--awb-color2);--awb-hotspot-background-color:var(--awb-color6);--awb-pos-x:25.0%;--awb-pos-y:0.0%;\" class=\"awb-image-hotspots-hotspot awb-image-hotspots-hotspot-2\" role=\"button\" tabindex=\"0\" data-awb-toggle-image-hotspot-popover=\"true\" data-title=\"Bauernwirt\" data-content=\"Der Bauernwirt bietet charmante Atmosph\u00e4re auf 120 m\u00b2. Hier finden bis zu 80 Personen Platz, um an einem Event teilzunehmen.\" data-trigger=\"hover focus\" data-placement=\"auto bottom\"><i class=\"fa-glass-cheers fas\"><\/i> 80 persone<\/a><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:1em;--awb-margin-bottom-large:2px;--awb-spacing-left-large:1em;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:1em;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"--awb-popover-heading-background-color:var(--awb-color2);--awb-popover-content-background-color:rgba(111,149,113,0.3);--awb-popover-text-color:var(--awb-color7);--awb-popover-border-color:var(--awb-color1);\" class=\"awb-image-hotspots awb-image-hotspots-3\"><div class=\"awb-image-hotspots-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp\" alt=\"Eventlocation am Berg in K\u00e4rnten, G\u00e4ste am Feiern ausgelassen im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim\" width=\"1000\" height=\"667\" title=\"Eventlocation am Berg\" class=\"awb-image-hotspots-image wp-image-476\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-768x512.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie-800x534.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><a style=\"--awb-hotspot-text-color:var(--awb-color2);--awb-hotspot-background-color:var(--awb-color6);--awb-pos-x:25.0%;--awb-pos-y:0.0%;\" class=\"awb-image-hotspots-hotspot awb-image-hotspots-hotspot-3\" role=\"button\" tabindex=\"0\" data-awb-toggle-image-hotspot-popover=\"true\" data-title=\"Wild\u00adf\u00fctterung\" data-content=\"Tagen in charmanter Atmosph\u00e4re k\u00f6nnen in unseren Raum \u201eWildf\u00fctterung\u201c bis zu 100 Personen.\" data-trigger=\"hover focus\" data-placement=\"auto bottom\"><i class=\"fa-glass-cheers fas\"><\/i> 100 persone<\/a><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_4 1_4 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-margin-top-small:1em;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"--awb-popover-heading-background-color:var(--awb-color2);--awb-popover-content-background-color:rgba(111,149,113,0.3);--awb-popover-text-color:var(--awb-color7);--awb-popover-border-color:var(--awb-color1);\" class=\"awb-image-hotspots awb-image-hotspots-4\"><div class=\"awb-image-hotspots-wrapper\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie.webp\" alt=\"Veranstaltungsraum mit ausgew\u00e4hlten Weinen f\u00fcr Hochzeiten, Firmenfeiern und private Anl\u00e4sse \u2013 Eventlocation mitten in St. Oswald, K\u00e4rnten.\" width=\"1000\" height=\"666\" title=\"Feste feiern im Slow Travel Resort Kirchleitn\" class=\"awb-image-hotspots-image wp-image-472\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-300x200.webp 300w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-400x266.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-768x511.webp 768w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/muhle-e1632477782856-Kopie.webp 1000w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"\/><a style=\"--awb-hotspot-text-color:var(--awb-color2);--awb-hotspot-background-color:var(--awb-color6);--awb-pos-x:25.0%;--awb-pos-y:0.0%;\" class=\"awb-image-hotspots-hotspot awb-image-hotspots-hotspot-4\" role=\"button\" tabindex=\"0\" data-awb-toggle-image-hotspot-popover=\"true\" data-title=\"Alte M\u00fchle\" data-content=\"Kleine Details wie die rustikale Holzbr\u00fccke inmitten des Raums und einzigartige Dekoration verschaffen diesem Ort Besonderheit.\" data-trigger=\"hover focus\" data-placement=\"auto bottom\"><i class=\"fa-glass-cheers fas\"><\/i> 60-70 persone<\/a><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6.5em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-6 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\"><p class=\"p1\">Festeggia il tuo giorno speciale in montagna<\/p><\/h2><\/div><div class=\"fusion-title title fusion-title-7 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;line-height:1.2;\">Che si tratti di una festa di famiglia, di un anniversario aziendale, di una comunione, di un addio al celibato\/nubilato, di una festa di compleanno, da noi puoi festeggiare ogni occasione come si deve!<\/h3><\/div><div class=\"fusion-text fusion-text-3\"><p>Godetevi non solo un&#8217;atmosfera unica e una calda ospitalit\u00e0, ma anche un servizio completo e professionale nel cuore dei monti Nockberge in Carinzia.<\/p>\n<p><i>Circondati da un ambiente elegante e da uno scenario che rende speciale ogni festa, festeggiate con noi spensierati con i vostri cari.<\/i><\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-1 fusion-button-span-yes fusion-button-default-type\" style=\"--awb-margin-top:1em;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_self\" data-hover=\"bg_slide_right\" href=\"tel:+4342408244\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Richiedi ora senza impegno la data desiderata per il tuo evento<\/span><i class=\"fa-phone-alt fas awb-button__icon awb-button__icon--default button-icon-right\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20em;--awb-padding-right:8em;--awb-padding-bottom:1em;--awb-padding-left:8em;--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/al-elmes-ULHxWq8reao-unsplash-1-scaled-e1632477762264-Kopie.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Eventlocation am Berg in K\u00e4rnten, G\u00e4ste am Feiern ausgelassen im Slow Travel Resort Kirchleitn in Bad Kleinkirchheim\" aria-label=\"Eventlocation am Berg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271000%27%20height%3D%27667%27%20viewBox%3D%270%200%201000%20667%27%3E%3Crect%20width%3D%271000%27%20height%3D%27667%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-fixed hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:6em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:0px;--awb-padding-left-small:1em;--awb-min-height:600px;--awb-background-image:linear-gradient(180deg, rgba(79,74,74,0.65) 0%,rgba(79,74,74,0.56) 100%),url(https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/hg_essen.webp);;--awb-background-size:cover;--awb-flex-wrap:wrap;background-attachment:fixed;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-8 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifplane&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Godere in modo sostenibile \u2013 festeggiare consapevolmente<\/h3><\/div><div class=\"fusion-title title fusion-title-9 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:22px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;\">La sostenibilit\u00e0 \u00e8 particolarmente importante per noi anche durante gli eventi<\/h4><\/div><div class=\"fusion-text fusion-text-4\" style=\"--awb-text-color:var(--awb-color1);--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p>Per pause caff\u00e8, men\u00f9 o buffet utilizziamo esclusivamente ingredienti di alta qualit\u00e0, possibilmente provenienti dalla regione. Insieme al nostro team di cucina, creiamo un&#8217;offerta che soddisfi i vostri gusti e sia adattata individualmente ai vostri desideri. <\/p>\n<p>Da noi nascono idee speciali, momenti creativi e veri incontri in mezzo alla natura.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6.5em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:3.84%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-10 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Matrimonio in montagna in Carinzia<\/h3><\/div><div class=\"fusion-title title fusion-title-11 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;line-height:1.2;\">DITE &#8220;S\u00cc&#8221; \u2013 nel cuore dei monti Nockberge a 1.300 metri<\/h4><\/div><div class=\"fusion-text fusion-text-5\"><p><b>Ogni coppia di sposi ha desideri individuali e idee proprie sul giorno pi\u00f9 bello della loro vita. Vogliamo darvi lo spazio per realizzare le vostre idee insieme a noi. <\/b><\/p>\n<p>Sposarsi su un prato fiorito, in mezzo a una natura mozzafiato, festeggiare allegramente fino alle prime ore del mattino \u2013 e lasciarsi viziare da cibi deliziosi e bevande rinfrescanti: tutto questo \u00e8 possibile da noi.<\/p>\n<p>Vivete il vostro matrimonio da sogno personale tra le montagne carinziane, circondati dal parco della biosfera UNESCO Nockberge.<\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_blank\" rel=\"noopener noreferrer\" data-hover=\"bg_slide_right\" role=\"button\" href=\"https:\/\/www.kirchleitn.com\/it\/richiesta-rapida\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-right\">Fissa ora una visita senza impegno alla location del matrimonio<\/span><span class=\"fusion-button-icon-divider button-icon-divider-right\"><i class=\"fa-heart fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20em;--awb-padding-right:8em;--awb-padding-bottom:1em;--awb-padding-left:8em;--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_9.webp&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_9.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Brautpaar mit Strau\u00df vor uriger Holzkulisse \u2013 romantische Hochzeitslocation im Slow Travel Resort Kirchleitn in St. Oswald bei Bad Kleinkirchheim.\" aria-label=\"Hochzeit in K\u00e4rnten \u2013 Brautpaar\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27801%27%20viewBox%3D%270%200%201200%20801%27%3E%3Crect%20width%3D%271200%27%20height%3D%27801%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\" style=\"--more-btn-alignment:center;\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-6 fusion-gallery-layout-grid fusion-gallery-1\"><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5.jpg\" width=\"1200\" height=\"800\" alt=\"Gli sposi formano un cuore con le mani \u2013 scena simbolica di un matrimonio nello Slow Travel Resort Kirchleitn in Carinzia.\" title=\"Momenti di matrimonio pieni d&#8217;amore\" aria-label=\"Momenti di matrimonio pieni d&#8217;amore\" class=\"img-responsive wp-image-2822\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-5.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2.jpg\" width=\"1200\" height=\"800\" alt=\"Calici di spumante e composizioni floreali su tavoli alti all&#039;aperto \u2013 Festa nell&#039;area esterna dello Slow Travel Resort Kirchleitn a Bad Kleinkirchheim.\" title=\"Festeggiare all&#8217;aperto nel villaggio turistico\" aria-label=\"Festeggiare all&#8217;aperto nel villaggio turistico\" class=\"img-responsive wp-image-2820\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-2.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg\" width=\"1200\" height=\"800\" alt=\"Location decorata in modo romantico per matrimoni e occasioni speciali nello Slow Travel Resort Kirchleitn in Carinzia.\" title=\"Festeggiare il matrimonio nella location per eventi Kirchleitn\" aria-label=\"Festeggiare il matrimonio nella location per eventi Kirchleitn\" class=\"img-responsive wp-image-2821\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-3.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events.webp\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events.webp\" width=\"1920\" height=\"1280\" alt=\"Gli sposi corrono sull&#039;alpe di Bad Kleinkirchheim \u2013 momenti di matrimonio indimenticabili nel cuore del paesaggio montano carinziano.\" title=\"Sposi sull&#8217;alpe\" aria-label=\"Sposi sull&#8217;alpe\" class=\"img-responsive wp-image-2823\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-200x133.webp 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-400x267.webp 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-600x400.webp 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-800x533.webp 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events-1200x800.webp 1200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/events.webp 1920w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7.jpg\" width=\"1200\" height=\"800\" alt=\"Torta nuziale con fiori discreti e decorazioni naturali \u2013 Festa elegante nello Slow Travel Resort Kirchleitn a Bad Kleinkirchheim.\" title=\"Torta nuziale\" aria-label=\"Torta nuziale\" class=\"img-responsive wp-image-2824\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-7.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4.jpg\" rel=\"noreferrer\" data-rel=\"iLightbox[gallery_image_1]\" class=\"fusion-lightbox\" target=\"_self\"><img decoding=\"async\" src=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4.jpg\" width=\"1200\" height=\"800\" alt=\"Tavoli decorati a festa nella location per eventi Tenne \u2013 elegante festa di matrimonio nel cuore delle montagne nello Slow Travel Resort Kirchleitn a St. Oswald.\" title=\"Tavoli imbanditi a festa nella location per eventi Tenne\" aria-label=\"Tavoli imbanditi a festa nella location per eventi Tenne\" class=\"img-responsive wp-image-2819\" srcset=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4-200x133.jpg 200w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4-400x267.jpg 400w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4-600x400.jpg 600w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4-800x533.jpg 800w, https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4.jpg 1200w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 397px, (min-width: 712px) 595px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container has-pattern-background has-mask-background fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:center bottom;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:4em;--awb-padding-right:6em;--awb-padding-bottom:4em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-background-image:linear-gradient(180deg, rgba(89,120,90,0.88) 0%,rgba(111,149,113,0.62) 100%),url(https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/Hochzeit_8.webp);;--awb-background-size:cover;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-12 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Il vostro matrimonio \u2013 unico come voi<\/h4><\/div><div class=\"fusion-title title fusion-title-13 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;line-height:1.2;\">Che si tratti di boho, vintage, rustic o fine art, nella nostra location per matrimoni tra le montagne carinziane celebrate l&#8217;amore, la felicit\u00e0 e i momenti speciali che rimarranno per sempre con i vostri cari<\/h4><\/div><div class=\"fusion-text fusion-text-6\" style=\"--awb-line-height:1.4;--awb-text-color:var(--awb-color1);--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:400;\"><p>Per noi \u00e8 importante che vi sentiate completamente a vostro agio e che possiate realizzare il vostro stile. Con tanta esperienza, cuore e intuito, vi accompagniamo dalla prima idea al grande giorno. <\/p>\n<p>Non vediamo l&#8217;ora di dare vita insieme ai vostri desideri.<\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:2em;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_blank\" rel=\"noopener noreferrer\" data-hover=\"bg_slide_right\" role=\"button\" href=\"mailto:booknow@slowtravelling.com\"><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-right\">Invia ora una richiesta non vincolante<\/span><span class=\"fusion-button-icon-divider button-icon-divider-right\"><i class=\"fa-envelope fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-14 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color7);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\"><p class=\"p1\">Meeting aziendali<br \/>&amp; eventi di team building in Carinzia<\/p><\/h3><\/div><div class=\"fusion-text fusion-text-7\" style=\"--awb-text-color:var(--awb-color7);\"><p><b>Kirchleitn crea un&#8217;atmosfera di ispirazione e relax. Da noi, i meeting creativi e ricchi di idee possono essere meravigliosamente combinati con escursioni rilassanti e rigeneranti nei monti Nockberge. <\/b><\/p>\n<p>Che si tratti di team building, gite aziendali o feste di Natale, nel nostro resort ci sono innumerevoli possibilit\u00e0 per ogni tipo di evento aziendale.<\/p>\n<p>Saremo lieti di occuparci del vostro programma di contorno, ad esempio visite guidate attraverso il parco della biosfera, corsi di cucina comuni o cene speciali. Non lasciamo nulla di intentato e pianifichiamo insieme il vostro evento perfetto. <\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-4 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:2em;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_blank\" rel=\"noopener noreferrer\" data-hover=\"bg_slide_right\" role=\"button\" href=\"mailto:booknow@slowtravelling.com\"><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-right\">Richiedi ora un&#8217;offerta per il tuo evento aziendale<\/span><span class=\"fusion-button-icon-divider button-icon-divider-right\"><i class=\"fa-angle-double-right fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp&#039;);--awb-bg-position:right top;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/firmentagung.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Seminarraum im Slow Travel Resort Kirchleitn \u2013 ideale Location f\u00fcr Tagungen, Workshops und Firmenveranstaltungen in K\u00e4rnten.\" aria-label=\"Seminare und Tagungen im Feriendorf\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-11 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:4em;--awb-padding-left:6em;--awb-padding-top-small:1em;--awb-padding-right-small:1em;--awb-padding-bottom-small:1em;--awb-padding-left-small:1em;--awb-background-color:rgba(1,76,60,0);--awb-background-image:linear-gradient(180deg, var(--awb-custom_color_2) 0%,var(--awb-custom_color_2) 100%);--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-15 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifplane&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Crescere insieme nei monti Nockberge<br \/>\u2013 Consigli per attivit\u00e0 di team building diversificate<\/h4><\/div><div class=\"fusion-text fusion-text-8\" style=\"--awb-font-size:24px;--awb-text-color:var(--awb-color1);--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p>Che si tratti di un&#8217;avventura all&#8217;aperto insieme, di un&#8217;escursione alla scoperta delle erbe aromatiche o di un corso di cucina comune: a Kirchleitn i dipendenti si conoscono al di fuori della routine quotidiana dell&#8217;ufficio.<\/p>\n<\/div><div class=\"fusion-text fusion-text-9\" style=\"--awb-text-color:var(--awb-color1);--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:400;\"><p>Le esperienze condivise all&#8217;aria aperta rafforzano lo spirito di squadra, promuovono la coesione e creano ricordi preziosi \u2013 un&#8217;opportunit\u00e0 per ridere insieme come squadra, costruire fiducia e rafforzare la collaborazione.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_4 1_4 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/248_0045_LR_Kirchleitn\u00a9gert_perauer-e1636639811770-Kopie.webp&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:2;--awb-margin-top-small:1em;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:1em;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/248_0045_LR_Kirchleitn\u00a9gert_perauer-e1636639811770-Kopie.webp\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-end\" style=\"--awb-padding-top:1em;--awb-padding-right:1em;--awb-padding-left:1em;--awb-bg-color:rgba(243,242,239,0.62);--awb-bg-color-hover:rgba(243,242,239,0.62);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:2em;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-16 fusion-sep-none fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:0px;--awb-margin-right:1em;--awb-margin-bottom:0px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:25px;\"><h5 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;font-size:1em;\">Specialit\u00e0 carinziane<br \/>Corso di cucina<\/h5><\/div><div class=\"fusion-text fusion-text-10\" style=\"--awb-font-size:13px;--awb-margin-top:1em;--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Prezzo su richiesta<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_1_4 1_4 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/ivan-torres-MQUqbmszGGM-unsplash-1-scaled-e1632478141192-Kopie.webp&#039;);--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:1;--awb-margin-top-small:1em;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/ivan-torres-MQUqbmszGGM-unsplash-1-scaled-e1632478141192-Kopie.webp\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-end\" style=\"--awb-padding-top:1em;--awb-padding-right:1em;--awb-padding-left:1em;--awb-bg-color:rgba(243,242,239,0.62);--awb-bg-color-hover:rgba(243,242,239,0.62);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:2em;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-17 fusion-sep-none fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:0px;--awb-margin-right:1em;--awb-margin-bottom:0px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:25px;\"><h5 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;font-size:1em;\">Fare la pizza da soli<br \/>Corso di cucina<\/h5><\/div><div class=\"fusion-text fusion-text-11\" style=\"--awb-font-size:13px;--awb-margin-top:1em;--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Prezzo su richiesta<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_1_4 1_4 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/artur-rutkowski-h2CPeqTzaaY-unsplash-1-scaled-e1632478163495-Kopie.webp&#039;);--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:3;--awb-spacing-right-small:1.92%;--awb-margin-bottom-small:1em;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/artur-rutkowski-h2CPeqTzaaY-unsplash-1-scaled-e1632478163495-Kopie.webp\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-end\" style=\"--awb-padding-top:1em;--awb-padding-right:1em;--awb-padding-left:1em;--awb-bg-color:rgba(243,242,239,0.62);--awb-bg-color-hover:rgba(243,242,239,0.62);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:2em;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-18 fusion-sep-none fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:0px;--awb-margin-right:1em;--awb-margin-bottom:0px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:25px;\"><h5 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;font-size:1em;\">Visita ai nostri<br \/>fornitori<\/h5><\/div><div class=\"fusion-text fusion-text-12\" style=\"--awb-font-size:13px;--awb-margin-top:1em;--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Prezzo su richiesta<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_1_4 1_4 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/pexels-pixabay-48137-1-scaled-e1632477986841-Kopie.webp&#039;);--awb-bg-size:cover;--awb-width-large:25%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:7.68%;--awb-width-medium:25%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:7.68%;--awb-width-small:100%;--awb-order-small:4;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/pexels-pixabay-48137-1-scaled-e1632477986841-Kopie.webp\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_1 1_1 fusion-flex-column fusion-flex-align-self-flex-end\" style=\"--awb-padding-top:1em;--awb-padding-right:1em;--awb-padding-left:1em;--awb-bg-color:rgba(243,242,239,0.62);--awb-bg-color-hover:rgba(243,242,239,0.62);--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:2em;--awb-spacing-right-large:1em;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1em;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1em;--awb-spacing-left-medium:1em;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-end fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-19 fusion-sep-none fusion-title-text fusion-title-size-five\" style=\"--awb-margin-top:0px;--awb-margin-right:1em;--awb-margin-bottom:0px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:25px;\"><h5 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;font-size:1em;\">Tour guidato nel parco della biosfera<\/h5><\/div><div class=\"fusion-text fusion-text-13\" style=\"--awb-font-size:13px;--awb-margin-top:1em;--awb-text-font-family:&quot;Outfit&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Prezzo su richiesta<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-12 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20em;--awb-padding-right:8em;--awb-padding-bottom:1em;--awb-padding-left:8em;--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/herbstkind1.webp&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/herbstkind1.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Kind spielt mit bunten Herbstbl\u00e4ttern beim Familienurlaub in Bad Kleinkirchheim \u2013 goldene Herbsttage in K\u00e4rnten genie\u00dfen.\" aria-label=\"Kind mit Herbstlaub in Bad Kleinkirchheim\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27801%27%20viewBox%3D%270%200%201200%20801%27%3E%3Crect%20width%3D%271200%27%20height%3D%27801%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-23 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-20 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h4 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Congressi a misura di famiglia<\/h4><\/div><div class=\"fusion-title title fusion-title-21 fusion-sep-none fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:var(--awb-color5);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:20px;\"><h5 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;Outfit&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;line-height:1.2;\">Sale per eventi attrezzate professionalmente in Carinzia rendono il vostro congresso, il vostro seminario o la vostra festa un&#8217;esperienza di successo.<\/h5><\/div><div class=\"fusion-text fusion-text-14\"><p>Anche la vostra famiglia si sentir\u00e0 a suo agio da noi. Nel cuore del villaggio turistico, voi e i vostri bambini troverete aree <a href=\"https:\/\/www.kirchleitn.com\/it\/vacanze-con-bambini-a-bad-kleinkirchheim-carinzia\/\">dedicate ai bambini<\/a> e, grazie alla K\u00e4rnten Card inclusa, numerose ed entusiasmanti mete escursionistiche nei dintorni del parco della biosfera UNESCO Nockberge. <\/p>\n<p>Approfittate delle nostre interessanti offerte per notti aggiuntive e trasformate il vostro congresso in una rilassante vacanza breve tra le montagne carinziane.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-13 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-24 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-22 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color6);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:30px;\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\">Alloggiare direttamente nell&#8217;area dell&#8217;evento<br \/>\u2013 rimanere rilassati invece di tornare a casa<\/h2><\/div><div class=\"fusion-text fusion-text-15\"><p data-start=\"186\" data-end=\"431\">Dopo una giornata piena di emozioni, risate e momenti speciali, non dovrete pi\u00f9 affrontare il viaggio di ritorno. Direttamente nel villaggio turistico di Kirchleitn, voi e i vostri ospiti potrete pernottare comodamente, in un ambiente accogliente e nel cuore dell&#8217;azione. <\/p>\n<p data-start=\"433\" data-end=\"719\">Cos\u00ec la vostra festa si trasforma senza soluzione di continuit\u00e0 in una pausa rilassante. La sera ripercorrete le esperienze, vi godete un bicchiere di vino o una piacevole chiacchierata davanti alla stufa in maiolica e la mattina dopo iniziate nuove avventure ricaricati. <\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-5 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:2em;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_blank\" rel=\"noopener noreferrer\" data-hover=\"bg_slide_right\" role=\"button\" href=\"https:\/\/www.kirchleitn.com\/it\/appartamenti-a-bad-kleinkirchheim-carinzia\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-right\">Maggiori informazioni sugli appartamenti a Kirchleitn<\/span><span class=\"fusion-button-icon-divider button-icon-divider-right\"><i class=\"fa-angle-double-right fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-25 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:20em;--awb-padding-right:8em;--awb-padding-bottom:1em;--awb-padding-left:8em;--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Aussenansicht\u00a9Slow-Travel-Resort_10-Kopie.webp&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Aussenansicht\u00a9Slow-Travel-Resort_10-Kopie.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Casa vacanze alpina a Bad Kleinkirchheim nello Slow Travel Resort Kirchleitn in Carinzia \u2013 direttamente accanto al parco giochi acquatico.\" aria-label=\"Casa vacanze a Bad Kleinkirchheim\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-14 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-26 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/feiern.webp&#039;);--awb-bg-position:right top;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-block fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/10\/feiern.webp\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Gruppe feiert in gem\u00fctlicher Atmosph\u00e4re im Slow Travel Resort Kirchleitn \u2013 gesellige Momente in den Eventlocations direkt im Feriendorf\" aria-label=\"Gemeinsam feiern im Slow Travel Resort Kirchleitn\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271282%27%20viewBox%3D%270%200%201920%201282%27%3E%3Crect%20width%3D%271920%27%20height%3D%271282%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-27 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:2em;--awb-padding-right:6em;--awb-padding-bottom:2em;--awb-padding-left:6em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:2em;--awb-padding-left-small:1em;--awb-bg-color:rgba(204,136,0,0.11);--awb-bg-color-hover:rgba(204,136,0,0.11);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-23 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color7);--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-font-size:40px;\"><h3 class=\"fusion-title-heading title-heading-left\" style=\"font-family:&quot;HarlowSerifRegluar&quot;;font-style:normal;font-weight:400;margin:0;font-size:1em;\"><p class=\"p1\">Il tuo evento da noi<\/p><\/h3><\/div><div class=\"fusion-text fusion-text-16\" style=\"--awb-text-color:var(--awb-color7);\"><p>Durante un colloquio personale, saremo lieti di prenderci il tempo necessario per discutere con calma le vostre idee e tutti i dettagli importanti.<\/p>\n<\/div><div ><a class=\"fusion-button button-flat fusion-button-default-size button-custom fusion-button-default button-6 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:2em;--button_accent_color:var(--awb-color1);--button_accent_hover_color:var(--awb-color1);--button_border_hover_color:var(--awb-color1);--button-border-radius-top-left:0;--button-border-radius-top-right:0;--button-border-radius-bottom-right:0;--button-border-radius-bottom-left:0;--button_gradient_top_color:var(--awb-custom_color_1);--button_gradient_bottom_color:var(--awb-custom_color_1);--button_gradient_top_color_hover:var(--awb-color5);--button_gradient_bottom_color_hover:var(--awb-color5);\" target=\"_blank\" rel=\"noopener noreferrer\" data-hover=\"bg_slide_right\" role=\"button\" href=\"mailto:booknow@slowtravelling.com\"><span class=\"fusion-button-text awb-button__text awb-button__text--default fusion-button-text-right\"> Fissa un colloquio personale<\/span><span class=\"fusion-button-icon-divider button-icon-divider-right\"><i class=\"fa-paper-plane fas awb-button__icon awb-button__icon--default\" aria-hidden=\"true\"><\/i><\/span><\/a><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-15 fusion-flex-container has-pattern-background has-mask-background hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-left:0px;--awb-padding-right-small:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-justify-content-space-between fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-28 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-padding-top:4em;--awb-padding-right:8em;--awb-padding-bottom:4em;--awb-padding-left:8em;--awb-padding-top-small:2em;--awb-padding-right-small:1em;--awb-padding-bottom-small:0px;--awb-padding-left-small:1em;--awb-bg-color:var(--awb-color2);--awb-bg-color-hover:var(--awb-color2);--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:1;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column\"><div class=\"fusion-text fusion-text-17 fusion-text-no-margin\" style=\"--awb-font-size:40px;--awb-letter-spacing:0px;--awb-text-color:var(--awb-color4);--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-text-font-family:&quot;HarlowSerifRegluar&quot;;--awb-text-font-style:normal;--awb-text-font-weight:400;\"><p>FAQ&#8217;s Location per eventi in montagna in Carinzia<\/p>\n<\/div><div class=\"accordian fusion-accordian\" style=\"margin-top:1em;margin-bottom:1em;--awb-margin-top:1em;--awb-margin-bottom:1em;--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:20px;--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:rgba(242,243,245,0);--awb-divider-hover-color:rgba(242,243,245,0);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color7);--awb-content-color:var(--awb-color7);--awb-icon-box-color:var(--awb-color4);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-toggle-active-accent-color:var(--awb-color7);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-2818-1\"><div class=\"fusion-panel panel-default panel-d757e38c656e30814 fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_d757e38c656e30814\"><a aria-expanded=\"false\" aria-controls=\"d757e38c656e30814\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#d757e38c656e30814\" href=\"#d757e38c656e30814\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Dove posso sposarmi in montagna in Carinzia?<\/span><\/a><\/h4><\/div><div id=\"d757e38c656e30814\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_d757e38c656e30814\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Nel Slow Travel Resort Kirchleitn a Bad Kleinkirchheim potete sposarvi nel cuore dei monti Nockberge in Carinzia a 1.300 metri di altitudine. Circondati dalla natura e dalla tranquillit\u00e0, celebrate matrimoni romantici e feste di nozze eleganti. Voi e i vostri ospiti pernotterete comodamente in accoglienti appartamenti direttamente nel villaggio turistico.  <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-24f247c746440f984 fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_24f247c746440f984\"><a aria-expanded=\"false\" aria-controls=\"24f247c746440f984\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#24f247c746440f984\" href=\"#24f247c746440f984\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quale location per matrimoni per pi\u00f9 di 100 persone in Carinzia?<\/span><\/a><\/h4><\/div><div id=\"24f247c746440f984\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_24f247c746440f984\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Lo Slow Travel Resort Kirchleitn offre spazio per matrimoni con un massimo di 500 invitati. Le sale per eventi possono essere progettate in diversi stili \u2013 dal boho al fine art \u2013 e per l&#8217;intrattenimento dei bambini ci sono le aree dedicate ai bambini nel cuore del villaggio turistico. Le case alpine in legno e lo scenario montano conferiscono al vostro matrimonio un&#8217;atmosfera unica.  <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-5098755daff498aff fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_5098755daff498aff\"><a aria-expanded=\"false\" aria-controls=\"5098755daff498aff\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#5098755daff498aff\" href=\"#5098755daff498aff\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Dove si pu\u00f2 festeggiare un battesimo in Carinzia?<\/span><\/a><\/h4><\/div><div id=\"5098755daff498aff\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_5098755daff498aff\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Nello Slow Travel Resort Kirchleitn \u00e8 possibile celebrare i battesimi in un piccolo o grande cerchio familiare. La cucina regionale vizia gli ospiti, mentre i bambini si divertono nella sala giochi interna, sulla pista per Bobby Car o in altre aree giochi del villaggio. Cos\u00ec gli adulti possono festeggiare spensierati e anche i pi\u00f9 piccoli non si annoiano mai.  <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-e8518a82f69e3cb55 fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_e8518a82f69e3cb55\"><a aria-expanded=\"false\" aria-controls=\"e8518a82f69e3cb55\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#e8518a82f69e3cb55\" href=\"#e8518a82f69e3cb55\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quale location per eventi in Carinzia per feste aziendali<\/span><\/a><\/h4><\/div><div id=\"e8518a82f69e3cb55\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_e8518a82f69e3cb55\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Lo Slow Travel Resort in Carinzia offre sale polivalenti per feste aziendali, seminari ed eventi di team building per un massimo di 500 persone. Combinate meeting produttivi con attivit\u00e0 all&#8217;aperto o <a href=\"https:\/\/www.kirchleitn.com\/it\/vacanze-escursionistiche-con-bambini-a-bad-kleinkirchheim-carinzia\/\">escursioni<\/a>, mentre i partecipanti e le loro famiglie possono pernottare direttamente in loco nel villaggio turistico. <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-c1dd5ec25cd28bd11 fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_c1dd5ec25cd28bd11\"><a aria-expanded=\"false\" aria-controls=\"c1dd5ec25cd28bd11\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#c1dd5ec25cd28bd11\" href=\"#c1dd5ec25cd28bd11\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Dove si pu\u00f2 festeggiare in modo sostenibile in Carinzia?<\/span><\/a><\/h4><\/div><div id=\"c1dd5ec25cd28bd11\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_c1dd5ec25cd28bd11\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>In linea con il <a href=\"https:\/\/www.slowtravelling.com\/slow-travel-urlaub\/\" target=\"_blank\" rel=\"noopener\">concetto di Slow Travel<\/a>, la festa sostenibile \u00e8 al centro dello Slow Travel Resort Kirchleitn. Per matrimoni, compleanni o feste aziendali vengono utilizzati ingredienti regionali e men\u00f9 stagionali. Sale progettate con cura e possibilit\u00e0 di pernottamento in loco combinano la sostenibilit\u00e0 con momenti indimenticabili.  <\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-501636b9ea33a1dc1 fusion-toggle-has-divider\" style=\"--awb-content-font-size:20px;--awb-content-line-height:1.4;--awb-content-font-family:&quot;Outfit&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;--awb-title-font-size:20px;--awb-title-line-height:1.4;--awb-title-color:var(--awb-color4);--awb-content-color:var(--awb-color7);\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_501636b9ea33a1dc1\"><a aria-expanded=\"false\" aria-controls=\"501636b9ea33a1dc1\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-2818-1\" data-target=\"#501636b9ea33a1dc1\" href=\"#501636b9ea33a1dc1\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Quale location in Carinzia per grandi feste di famiglia?<\/span><\/a><\/h4><\/div><div id=\"501636b9ea33a1dc1\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_501636b9ea33a1dc1\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Le grandi feste di famiglia sono particolarmente semplici nel villaggio turistico di Kirchleitn a Bad Kleinkirchheim. Mentre i bambini si divertono nelle aree giochi o sulla pista per Bobby Car, gli adulti possono festeggiare in tutta tranquillit\u00e0 e tutti gli ospiti pernottano direttamente nel villaggio. <\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-29 fusion_builder_column_1_2 1_2 fusion-flex-column fusion-flex-align-self-stretch\" style=\"--awb-bg-image:url(&#039;https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4.jpg&#039;);--awb-bg-position:center center;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:0%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:0%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:0%;--awb-spacing-left-medium:0%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-scroll-devices=\"small-visibility,medium-visibility,large-visibility\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-space-between fusion-content-layout-column fusion-empty-column-bg-image fusion-column-has-bg-image\" data-bg-url=\"https:\/\/www.kirchleitn.com\/wp-content\/uploads\/2025\/09\/Hochzeit-Slow-Travel-Resort-Kirchleitn-4.jpg\"><img decoding=\"async\" class=\"fusion-empty-dims-img-placeholder fusion-no-large-visibility fusion-no-medium-visibility\" alt=\"Tavoli decorati a festa nella location per eventi Tenne \u2013 elegante festa di matrimonio nel cuore delle montagne nello Slow Travel Resort Kirchleitn a St. Oswald.\" aria-label=\"Tavoli imbanditi a festa nella location per eventi Tenne\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271200%27%20height%3D%27800%27%20viewBox%3D%270%200%201200%20800%27%3E%3Crect%20width%3D%271200%27%20height%3D%27800%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\"><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2819,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-2818","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/pages\/2818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/comments?post=2818"}],"version-history":[{"count":0,"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/pages\/2818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/media\/2819"}],"wp:attachment":[{"href":"https:\/\/www.kirchleitn.com\/it\/wp-json\/wp\/v2\/media?parent=2818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}